{"id":461,"date":"2026-06-13T17:02:41","date_gmt":"2026-06-13T17:02:41","guid":{"rendered":"https:\/\/beuzekamp.nl\/reviews-2\/"},"modified":"2026-06-15T17:25:57","modified_gmt":"2026-06-15T17:25:57","slug":"beoordelingen","status":"publish","type":"page","link":"https:\/\/bonairebiggamefishing.com\/nl\/beoordelingen\/","title":{"rendered":"Reviews"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":928,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-461","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bonaire vischarter reviews | Fishtales<\/title>\n<meta name=\"description\" content=\"\u201cHet beste vissen van ons leven.\u201d Lees wat gasten zeggen over vissen met de Fishtales en kapitein Yuri op Bonaire.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bonairebiggamefishing.com\/nl\/beoordelingen\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bonaire vischarter reviews | Fishtales\" \/>\n<meta property=\"og:description\" content=\"\u201cHet beste vissen van ons leven.\u201d Lees wat gasten zeggen over vissen met de Fishtales en kapitein Yuri op Bonaire.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bonairebiggamefishing.com\/nl\/beoordelingen\/\" \/>\n<meta property=\"og:site_name\" content=\"Bonaire Big Game Fishing - Fishtales\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-15T17:25:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bonairebiggamefishing.com\/wp-content\/uploads\/2026\/06\/group-tuna-catch-fish-tales-boat-transom-bonaire-kralendijk.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1707\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bonairebiggamefishing.com\\\/nl\\\/beoordelingen\\\/\",\"url\":\"https:\\\/\\\/bonairebiggamefishing.com\\\/nl\\\/beoordelingen\\\/\",\"name\":\"Bonaire vischarter reviews | Fishtales\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bonairebiggamefishing.com\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bonairebiggamefishing.com\\\/nl\\\/beoordelingen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bonairebiggamefishing.com\\\/nl\\\/beoordelingen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bonairebiggamefishing.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/group-tuna-catch-fish-tales-boat-transom-bonaire-kralendijk.jpg\",\"datePublished\":\"2026-06-13T17:02:41+00:00\",\"dateModified\":\"2026-06-15T17:25:57+00:00\",\"description\":\"\u201cHet beste vissen van ons leven.\u201d Lees wat gasten zeggen over vissen met de Fishtales en kapitein Yuri op Bonaire.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bonairebiggamefishing.com\\\/nl\\\/beoordelingen\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bonairebiggamefishing.com\\\/nl\\\/beoordelingen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/bonairebiggamefishing.com\\\/nl\\\/beoordelingen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bonairebiggamefishing.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/group-tuna-catch-fish-tales-boat-transom-bonaire-kralendijk.jpg\",\"contentUrl\":\"https:\\\/\\\/bonairebiggamefishing.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/group-tuna-catch-fish-tales-boat-transom-bonaire-kralendijk.jpg\",\"width\":1707,\"height\":1280,\"caption\":\"Group With Tuna on the Fish Tales Boat | Bonaire Charter\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bonairebiggamefishing.com\\\/nl\\\/beoordelingen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bonairebiggamefishing.com\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reviews\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bonairebiggamefishing.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/bonairebiggamefishing.com\\\/nl\\\/\",\"name\":\"Bonaire Big Game Fishing - Fishtales\",\"description\":\"The best fishing charter on Bonaire\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bonairebiggamefishing.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bonaire vischarter reviews | Fishtales","description":"\u201cHet beste vissen van ons leven.\u201d Lees wat gasten zeggen over vissen met de Fishtales en kapitein Yuri op Bonaire.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bonairebiggamefishing.com\/nl\/beoordelingen\/","og_locale":"nl_NL","og_type":"article","og_title":"Bonaire vischarter reviews | Fishtales","og_description":"\u201cHet beste vissen van ons leven.\u201d Lees wat gasten zeggen over vissen met de Fishtales en kapitein Yuri op Bonaire.","og_url":"https:\/\/bonairebiggamefishing.com\/nl\/beoordelingen\/","og_site_name":"Bonaire Big Game Fishing - Fishtales","article_modified_time":"2026-06-15T17:25:57+00:00","og_image":[{"width":1707,"height":1280,"url":"https:\/\/bonairebiggamefishing.com\/wp-content\/uploads\/2026\/06\/group-tuna-catch-fish-tales-boat-transom-bonaire-kralendijk.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bonairebiggamefishing.com\/nl\/beoordelingen\/","url":"https:\/\/bonairebiggamefishing.com\/nl\/beoordelingen\/","name":"Bonaire vischarter reviews | Fishtales","isPartOf":{"@id":"https:\/\/bonairebiggamefishing.com\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bonairebiggamefishing.com\/nl\/beoordelingen\/#primaryimage"},"image":{"@id":"https:\/\/bonairebiggamefishing.com\/nl\/beoordelingen\/#primaryimage"},"thumbnailUrl":"https:\/\/bonairebiggamefishing.com\/wp-content\/uploads\/2026\/06\/group-tuna-catch-fish-tales-boat-transom-bonaire-kralendijk.jpg","datePublished":"2026-06-13T17:02:41+00:00","dateModified":"2026-06-15T17:25:57+00:00","description":"\u201cHet beste vissen van ons leven.\u201d Lees wat gasten zeggen over vissen met de Fishtales en kapitein Yuri op Bonaire.","breadcrumb":{"@id":"https:\/\/bonairebiggamefishing.com\/nl\/beoordelingen\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bonairebiggamefishing.com\/nl\/beoordelingen\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/bonairebiggamefishing.com\/nl\/beoordelingen\/#primaryimage","url":"https:\/\/bonairebiggamefishing.com\/wp-content\/uploads\/2026\/06\/group-tuna-catch-fish-tales-boat-transom-bonaire-kralendijk.jpg","contentUrl":"https:\/\/bonairebiggamefishing.com\/wp-content\/uploads\/2026\/06\/group-tuna-catch-fish-tales-boat-transom-bonaire-kralendijk.jpg","width":1707,"height":1280,"caption":"Group With Tuna on the Fish Tales Boat | Bonaire Charter"},{"@type":"BreadcrumbList","@id":"https:\/\/bonairebiggamefishing.com\/nl\/beoordelingen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bonairebiggamefishing.com\/nl\/"},{"@type":"ListItem","position":2,"name":"Reviews"}]},{"@type":"WebSite","@id":"https:\/\/bonairebiggamefishing.com\/nl\/#website","url":"https:\/\/bonairebiggamefishing.com\/nl\/","name":"Bonaire Big Game Fishing - Fishtales","description":"The best fishing charter on Bonaire","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bonairebiggamefishing.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/bonairebiggamefishing.com\/nl\/wp-json\/wp\/v2\/pages\/461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bonairebiggamefishing.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bonairebiggamefishing.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bonairebiggamefishing.com\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bonairebiggamefishing.com\/nl\/wp-json\/wp\/v2\/comments?post=461"}],"version-history":[{"count":1,"href":"https:\/\/bonairebiggamefishing.com\/nl\/wp-json\/wp\/v2\/pages\/461\/revisions"}],"predecessor-version":[{"id":462,"href":"https:\/\/bonairebiggamefishing.com\/nl\/wp-json\/wp\/v2\/pages\/461\/revisions\/462"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bonairebiggamefishing.com\/nl\/wp-json\/wp\/v2\/media\/928"}],"wp:attachment":[{"href":"https:\/\/bonairebiggamefishing.com\/nl\/wp-json\/wp\/v2\/media?parent=461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}